{"id":14865,"date":"2023-05-04T12:16:15","date_gmt":"2023-05-04T10:16:15","guid":{"rendered":"https:\/\/trailrunningmallorca.es\/?p=14865"},"modified":"2025-03-11T09:22:29","modified_gmt":"2025-03-11T08:22:29","slug":"hort-cova","status":"publish","type":"post","link":"https:\/\/trailrunningmallorca.es\/index.php\/2023\/05\/04\/hort-cova\/","title":{"rendered":"Hort de sa Cova, Port de Canonge, Cam\u00ed Pescadors, Pla des Ses Piotes"},"content":{"rendered":"<div class=\"responsive-tabs\">\n<h2 class=\"tabtitle\">Descripci\u00f3n<\/h2>\n<div class=\"tabcontent\">\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14868\" style=\"-webkit-box-shadow: 2px 3px 8px #444; -moz-box-shadow: 2px 3px 8px #444; box-shadow: 2px 3px 8px #444;\" src=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova.jpg\" alt=\"\" width=\"2000\" height=\"924\" srcset=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova.jpg 2000w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova-300x139.jpg 300w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova-1024x473.jpg 1024w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova-768x355.jpg 768w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mirador-hort-cova-1536x710.jpg 1536w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<div class=\"columna_izquierda\">\n<p style=\"color: red;\">Nota Importante: Pueden haber problemas de paso en la esplanada para ir hacia el Mirador dels Coloms, est\u00e1 en obras y hace pinta que lo van a cerrar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13213 alignleft\" src=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2015\/10\/Valldemossa-escudo.png\" alt=\"\" width=\"100\" height=\"117\"><\/p>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">Una vuelta de las m\u00e1s bonitas que he hecho por la zona de Valldemossa, que transcurre en Valldemossa y Esporles. Desde la urbanizaci\u00f3n George Sand, descendemos hacia la playa de s&#8217;Hort de sa Cova y llegamos al Port des Canonge por viejos caminos en buen estado. Subimos a Mirant de Mar por el cam\u00ed des Pescadors y desde all\u00ed por un senderito bien marcado, llegamos a la urbanizaci\u00f3n Nova Valldemossa. Por \u00faltimo, por el Pla de ses Piotes, llegamos a George Sand.<br \/>\n<\/div><\/div>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:5px 0;border-width:1px;border-color:#999999\"><\/div>\n<h5><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14866\" src=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mide-1.png\" alt=\"\" width=\"768\" height=\"371\" srcset=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mide-1.png 768w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/mide-1-300x145.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/h5>\n<h5 style=\"text-align: center;\"><em>Itinerario<\/em><\/h5>\n<div class=\"su-list\" style=\"margin-left:0px\">\n<ul>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Urbanizaci\u00f3n George Sand<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Mirador de sa Cova<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Cam\u00ed de s&#8217;Hort de sa Cova<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Font de sa Cova<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Finca de Son Sales<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Port des Canonge<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Cam\u00ed des Pescadors<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Mirant de Mar<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Urbanizaci\u00f3n Nova Valldemossa<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Pla de ses Piotes<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Mirador des Coloms<\/li>\n<li><i class=\"sui sui-tree\" style=\"color:#18831f\"><\/i> Urbanizaci\u00f3n George Sand<\/li>\n<\/ul>\n<\/div>\n<div class=\"su-divider su-divider-style-dotted\" style=\"margin:5px 0;border-width:1px;border-color:#999999\"><\/div>\n<span class=\"wpsdc-drop-cap\">U<\/span>\n<p>La ruta se inicia en la <strong>Urbanizaci\u00f3n George Sand<\/strong>, aparcamos delante del camino que se dirige al <strong>Mirador de Sa Cova<\/strong>, situado cerca de la carretera. Unos metros antes del mirador, por la derecha arranca el <strong>cam\u00ed de s&#8217;Hort de sa Cova<\/strong>, un bonito camino antiguo de herradura, que desciende rapidamente, tiene alg\u00fan tramo algo deshecho pero se baja sin problemas, la verdad que es una gozada bajar por este camino.<\/p>\n<p>A unos 700 metros de <strong>George Sand<\/strong>, el camino conecta con la pista ancha que baja desde la Urbanizaci\u00f3n. Seguimos por la ancha pista por la izquierda, un poco m\u00e1s adelante cruzamos el <strong>Torrent de s&#8217;Hort de sa Cova<\/strong> por un terreno con mucha piedra. Seguimos bajando y disfrutando y el terreno que pisamos se vuelve rojizo. Unos metros m\u00e1s adelante, volvemos a cruzar el torrente y pasamos cerca de la barrera de <strong>finca de s&#8217;Hort de sa Cova<\/strong> que dejamos a la izquierda.<\/p>\n<\/div>\n<div class=\"columna_derecha\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13212 alignleft\" src=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2015\/10\/VALLDEMOSSA.png\" alt=\"\" width=\"262\" height=\"246\"><\/p>\n<p>En pocos minutos llegamos a una esplanada, cerca de la playa y <strong>font de sa Cova<\/strong>, no bajamos hacia la playa, cruzamos en torrente, muy cerca desde brota el agua de la fuente y seguimos por un sendero por la izquierda, bien visible y f\u00e1cil de seguir, el cual asciende por la falda del <strong>Puig des Moro<\/strong>, dentro de un bonito pinar.<\/p>\n<p>M\u00e1s adelante tenemos que superar una valla met\u00e1lica por un botador de madera. Continuamos unos pocos minutos y salimos a un camino que se dirige a la <strong>finca de Son Sales<\/strong>, pasamos por delante de las bonitas casas y seguimos por el camino ancho que va descendiendo hacia una barrera met\u00e1lica que se puede superar por otro botador de madera.<\/p>\n<p>Pasada la barrera, se presentan dos caminos para llegar al <strong>Port des Canonge<\/strong>, el de la derecha llega por la costa y el de la izquierda, que cogemos nosotros, va por el interior, por un camino bien marcado. Llegamos a una casa de piedra, en d\u00f3nde el camino traza un marcado giro a la derecha y poco a poco entramos en las primeras casas del <strong>Port des Canonge<\/strong>, finalizando la primera parte de la ruta.<\/p>\n<p>Una primera parte espectacular y continuamos con la parte m\u00e1s dura de la ruta, ya que tendremos subida todo el tiempo, desde 20 metros de altitud hasta m\u00e1s de 500 metros en la <strong>urbanizaci\u00f3n Nova Valldemossa<\/strong>. Para ello, subimos hacia <strong>Mirant de Mar<\/strong>, por la ruta que ya conecemos bien, subiendo por el <strong>Cam\u00ed des Pescadors<\/strong>, un camino ancho que nos dejar\u00e1 en la parte superior del <strong>Port des Canonge<\/strong> y por un sendero, llegararemos a <strong>Mirant de Mar<\/strong>, un precioso lugar con un mirador natural precioso.<\/p>\n<p>Desde <strong>Mirant de Mar<\/strong>, nos desviamos por un sendero al lado de una casa en ruinas y que transcurre al lado de una pared seca, que divide los municipios de <em>Esporlas<\/em> y <em>Valldemossa<\/em>. Un poco m\u00e1s adelante, cruzamos la pared por un hueco abierto en ella y entramos en <em>Esporlas<\/em>, seguimos por el bonito sendero que se introduce en un bonito bosque y va ascendiendo rapidamente en zigzag, es precioso este camino, y en pleno verano un refugio de sombra.<\/p>\n<p>Tras un buen rato de subida, el sendero sale a un vial de la <strong>Urbanizaci\u00f3n Nova Valldemossa<\/strong> y seguimos por la carretera unos pocos metros y nos dirigimos mirando el GPS por un antiguo camino ancho hacia un escondido mirador, de forma piramidal y con unas preciosas vistas al mar, y al <strong>Port des Canonge<\/strong>, un maravilla.<\/p>\n<p>Volvemos a la carretera y seguimos por ella hasta llegar a una curva cerrada, por la que vamos un tramo sin apenas camino. Veremos los restos de un pared seca y con la ayuda del GPS, salimos a un nuevo camino que desciende hacia el <strong>Pla de ses Piotes<\/strong> y atraviesa el <strong>Torrent de s&#8217;Hort de sa Cova<\/strong>.<\/p>\n<p>Este camino se puede seguir sin problemas hasta llegar a una esplanada, que cruzamos para llegar al <strong>Mirador dels Coloms<\/strong>, tambi\u00e9n llamado <strong>Mirador de Son Ferrandell<\/strong>. Ya s\u00f3lo nos queda salir a la carretera de George Sand para finalizar esta maravillosa excursi\u00f3n.<\/p>\n<\/div>\n\n<\/div><h2 class=\"tabtitle\">Mapa topogr\u00e1fico<\/h2>\n<div class=\"tabcontent\">\n\n<p><a href=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14867 size-full\" style=\"-webkit-box-shadow: 2px 3px 8px #444; -moz-box-shadow: 2px 3px 8px #444; box-shadow: 2px 3px 8px #444;\" src=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1.jpg\" alt=\"\" width=\"1794\" height=\"1294\" srcset=\"https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1.jpg 1794w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1-236x170.jpg 236w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1-1024x739.jpg 1024w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1-768x554.jpg 768w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1-1536x1108.jpg 1536w, https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/2023\/05\/00-map-1-474x342.jpg 474w\" sizes=\"auto, (max-width: 1794px) 100vw, 1794px\" \/><\/a><\/p>\n\n<\/div><h2 class=\"tabtitle\">Galer\u00eda<\/h2>\n<div class=\"tabcontent\">\n\nngg_shortcode_0_placeholder\n<\/div><h2 class=\"tabtitle\">Track GPS<\/h2>\n<div class=\"tabcontent\">\n\n\r\n\t\t<div id=\"wpgpxmaps_14865_3646678\" class=\"wpgpxmaps\">\r\n\t\t\t<div id=\"map_14865_3646678_cont\" style=\"width:100%; height:450px;position:relative\" >\r\n\t\t\t\t<div id=\"map_14865_3646678\" style=\"width:100%; height:450px\"><\/div>\r\n\t\t\t\t<div id=\"wpgpxmaps_14865_3646678_osm_footer\" class=\"wpgpxmaps_osm_footer\" style=\"display:none;\"><span> &copy; <a href=\"http:\/\/www.openstreetmap.org\/copyright\">OpenStreetMap<\/a> contributors<\/span><\/div>\r\n\t\t\t<\/div>\r\n\t\t\t<canvas id=\"myChart_14865_3646678\" class=\"plot\" style=\"width:100%; height:450px\"><\/canvas>\r\n\t\t\t<div id=\"ngimages_14865_3646678\" class=\"ngimages\" style=\"display:none\"><\/div>\r\n\t\t\t<div id=\"report_14865_3646678\" class=\"report\"><\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<script type=\"text\/javascript\">\r\n\r\n\t\t\tjQuery(document).ready(function() {\r\n\r\n\t\t\t\tjQuery( \"#wpgpxmaps_14865_3646678\" ).wpgpxmaps( {\r\n\t\t\t\t\ttargetId           : \"14865_3646678\",\r\n\t\t\t\t\tmapType            : \"OSM1\",\r\n\t\t\t\t\tmapData            : [[39.7028000,2.5770670],[39.7028970,2.5770070],[39.7029190,2.5769000],[39.7029110,2.5767710],[39.7029120,2.5766420],[39.7029020,2.5765210],[39.7028980,2.5764700],[39.7028810,2.5765260],[39.7029410,2.5765090],[39.7030260,2.5764700],[39.7030950,2.5764510],[39.7031020,2.5764190],[39.7031260,2.5763550],[39.7031570,2.5763350],[39.7032210,2.5763970],[39.7033520,2.5763700],[39.7034500,2.5763460],[39.7034730,2.5762790],[39.7034440,2.5762200],[39.7035430,2.5761860],[39.7035630,2.5761000],[39.7034740,2.5760600],[39.7035500,2.5760620],[39.7036350,2.5760450],[39.7037460,2.5759980],[39.7038470,2.5759030],[39.7037470,2.5759020],[39.7036580,2.5758710],[39.7037400,2.5758010],[39.7038300,2.5757110],[39.7039050,2.5756100],[39.7038510,2.5755950],[39.7038060,2.5755430],[39.7038490,2.5754440],[39.7038940,2.5753430],[39.7039280,2.5752120],[39.7039330,2.5750960],[39.7039910,2.5749970],[39.7041000,2.5749410],[39.7041750,2.5748700],[39.7042060,2.5747950],[39.7042450,2.5746740],[39.7042720,2.5745410],[39.7043520,2.5744440],[39.7044420,2.5745110],[39.7045120,2.5745760],[39.7045830,2.5746810],[39.7046590,2.5746150],[39.7046810,2.5746820],[39.7047500,2.5746670],[39.7047390,2.5747770],[39.7048000,2.5748130],[39.7048230,2.5749110],[39.7049360,2.5749650],[39.7050640,2.5749820],[39.7052020,2.5749690],[39.7052890,2.5748630],[39.7053490,2.5747390],[39.7053770,2.5746000],[39.7053540,2.5745610],[39.7053310,2.5745210],[39.7053030,2.5745340],[39.7052640,2.5744810],[39.7052460,2.5743930],[39.7053500,2.5742680],[39.7053500,2.5741580],[39.7053580,2.5740220],[39.7053470,2.5739320],[39.7053770,2.5738250],[39.7053920,2.5737100],[39.7054340,2.5735840],[39.7054840,2.5734500],[39.7055250,2.5733420],[39.7055820,2.5732390],[39.7056430,2.5731050],[39.7056950,2.5729790],[39.7057250,2.5728660],[39.7058260,2.5727770],[39.7059140,2.5727080],[39.7059920,2.5726400],[39.7060980,2.5726250],[39.7061830,2.5725990],[39.7062760,2.5727180],[39.7064150,2.5729070],[39.7064900,2.5729960],[39.7065570,2.5730050],[39.7064590,2.5728120],[39.7063920,2.5726450],[39.7063570,2.5724830],[39.7062800,2.5723300],[39.7061670,2.5723090],[39.7060490,2.5722920],[39.7059520,2.5722890],[39.7058320,2.5722990],[39.7057100,2.5724130],[39.7055900,2.5725080],[39.7054910,2.5725540],[39.7053610,2.5726620],[39.7052520,2.5727620],[39.7052160,2.5728990],[39.7052140,2.5730260],[39.7051490,2.5731250],[39.7050260,2.5731850],[39.7049360,2.5731960],[39.7048140,2.5731800],[39.7047330,2.5731120],[39.7046540,2.5730130],[39.7045510,2.5729160],[39.7044080,2.5728210],[39.7043070,2.5727770],[39.7042130,2.5727510],[39.7040900,2.5726960],[39.7039690,2.5726690],[39.7038640,2.5726820],[39.7037050,2.5727290],[39.7036090,2.5727290],[39.7034950,2.5727510],[39.7034000,2.5727690],[39.7033180,2.5728180],[39.7031620,2.5728400],[39.7030510,2.5728570],[39.7029610,2.5728050],[39.7029080,2.5727180],[39.7028760,2.5726070],[39.7028350,2.5725030],[39.7027540,2.5723360],[39.7026700,2.5721720],[39.7026450,2.5720600],[39.7025820,2.5719790],[39.7024420,2.5719450],[39.7023570,2.5720090],[39.7022480,2.5720020],[39.7021310,2.5720120],[39.7020130,2.5720460],[39.7018470,2.5720360],[39.7017510,2.5720310],[39.7016180,2.5720560],[39.7014880,2.5720390],[39.7013890,2.5720300],[39.7012870,2.5720350],[39.7011640,2.5720710],[39.7010750,2.5721050],[39.7009580,2.5720640],[39.7008600,2.5720810],[39.7007540,2.5720240],[39.7007310,2.5718850],[39.7007330,2.5717340],[39.7007980,2.5715210],[39.7008530,2.5714180],[39.7008710,2.5711660],[39.7008110,2.5710370],[39.7007200,2.5709100],[39.7006250,2.5708040],[39.7005790,2.5706530],[39.7005970,2.5705110],[39.7005940,2.5702680],[39.7006260,2.5700780],[39.7006430,2.5698940],[39.7006010,2.5697540],[39.7005610,2.5696050],[39.7004960,2.5694570],[39.7004560,2.5692970],[39.7003690,2.5691030],[39.7002850,2.5689570],[39.7002730,2.5688190],[39.7003950,2.5686330],[39.7004710,2.5686760],[39.7005390,2.5688090],[39.7006170,2.5689390],[39.7007000,2.5689990],[39.7007700,2.5691260],[39.7007950,2.5692520],[39.7008280,2.5693810],[39.7008840,2.5694860],[39.7010510,2.5694780],[39.7010170,2.5693980],[39.7009500,2.5693230],[39.7009510,2.5691750],[39.7009900,2.5690680],[39.7009700,2.5688990],[39.7009200,2.5687530],[39.7009090,2.5686070],[39.7010010,2.5684310],[39.7010470,2.5682740],[39.7011030,2.5681100],[39.7010630,2.5679770],[39.7009810,2.5677580],[39.7009020,2.5676150],[39.7008360,2.5674970],[39.7007890,2.5673920],[39.7007670,2.5672700],[39.7008000,2.5671600],[39.7008520,2.5670440],[39.7008290,2.5671710],[39.7008630,2.5671630],[39.7009380,2.5670990],[39.7009080,2.5672150],[39.7009120,2.5674030],[39.7009990,2.5675440],[39.7010880,2.5676410],[39.7011710,2.5677190],[39.7013130,2.5678680],[39.7014070,2.5679890],[39.7014760,2.5680950],[39.7015260,2.5683500],[39.7015960,2.5684390],[39.7016520,2.5685530],[39.7016960,2.5687530],[39.7017020,2.5688700],[39.7017240,2.5689870],[39.7017850,2.5690950],[39.7018620,2.5691870],[39.7019820,2.5693160],[39.7021350,2.5692670],[39.7021310,2.5691330],[39.7021710,2.5690200],[39.7022030,2.5688480],[39.7022730,2.5686280],[39.7023260,2.5685120],[39.7024310,2.5683640],[39.7024660,2.5682540],[39.7025040,2.5681400],[39.7025500,2.5680250],[39.7026650,2.5681050],[39.7026990,2.5682210],[39.7027890,2.5683270],[39.7029140,2.5683550],[39.7030060,2.5682830],[39.7031130,2.5682650],[39.7031890,2.5684760],[39.7032370,2.5685950],[39.7033890,2.5686130],[39.7035770,2.5685510],[39.7037300,2.5684850],[39.7038620,2.5684170],[39.7040320,2.5683510],[39.7041160,2.5682780],[39.7041470,2.5681310],[39.7041920,2.5679320],[39.7042280,2.5677700],[39.7042720,2.5676550],[39.7044110,2.5675920],[39.7045080,2.5675510],[39.7046130,2.5675100],[39.7047610,2.5674610],[39.7048680,2.5673670],[39.7049810,2.5672790],[39.7050960,2.5672230],[39.7052550,2.5671510],[39.7053480,2.5671350],[39.7055220,2.5670760],[39.7056400,2.5670140],[39.7056910,2.5669240],[39.7056390,2.5668110],[39.7056220,2.5666560],[39.7056550,2.5665690],[39.7057180,2.5664320],[39.7058190,2.5663780],[39.7058920,2.5663430],[39.7058500,2.5662830],[39.7059520,2.5662170],[39.7059760,2.5660980],[39.7059360,2.5660570],[39.7058340,2.5658560],[39.7058200,2.5657220],[39.7058730,2.5656400],[39.7058230,2.5656310],[39.7058120,2.5656460],[39.7058270,2.5655370],[39.7059050,2.5654240],[39.7059380,2.5653810],[39.7059800,2.5654870],[39.7060120,2.5654260],[39.7059950,2.5654150],[39.7059820,2.5654430],[39.7059070,2.5654140],[39.7058330,2.5655210],[39.7057190,2.5655540],[39.7056200,2.5656130],[39.7055370,2.5656680],[39.7054010,2.5657410],[39.7052860,2.5658080],[39.7051950,2.5658840],[39.7051040,2.5658820],[39.7049860,2.5659310],[39.7048710,2.5659540],[39.7047790,2.5659560],[39.7046730,2.5659400],[39.7045850,2.5658910],[39.7045530,2.5657840],[39.7045030,2.5656950],[39.7044130,2.5656760],[39.7043010,2.5656210],[39.7041770,2.5655560],[39.7041020,2.5654880],[39.7040110,2.5654090],[39.7039210,2.5653490],[39.7038390,2.5652860],[39.7037270,2.5651980],[39.7036520,2.5650950],[39.7035800,2.5649520],[39.7035470,2.5647850],[39.7034820,2.5645970],[39.7034410,2.5644470],[39.7034190,2.5643340],[39.7033210,2.5642720],[39.7033040,2.5641590],[39.7032620,2.5640510],[39.7032080,2.5639000],[39.7031700,2.5637490],[39.7030990,2.5636370],[39.7029880,2.5636020],[39.7029190,2.5635180],[39.7028370,2.5634500],[39.7027630,2.5633820],[39.7026760,2.5632980],[39.7025880,2.5631740],[39.7025110,2.5630860],[39.7024070,2.5629580],[39.7023200,2.5628520],[39.7022120,2.5628590],[39.7020710,2.5629700],[39.7019240,2.5630390],[39.7018130,2.5631230],[39.7016960,2.5632770],[39.7016030,2.5634120],[39.7015010,2.5635140],[39.7013360,2.5634450],[39.7012360,2.5633570],[39.7011320,2.5632910],[39.7010120,2.5632080],[39.7009380,2.5630430],[39.7010450,2.5628320],[39.7011630,2.5626830],[39.7012760,2.5625780],[39.7013400,2.5624730],[39.7014030,2.5623260],[39.7014660,2.5621870],[39.7015570,2.5621260],[39.7017110,2.5620630],[39.7017510,2.5618760],[39.7016980,2.5617480],[39.7016300,2.5616500],[39.7015150,2.5615290],[39.7014490,2.5614530],[39.7015390,2.5613970],[39.7016320,2.5614700],[39.7017190,2.5615830],[39.7017900,2.5616560],[39.7018340,2.5615610],[39.7017740,2.5614560],[39.7017030,2.5613630],[39.7015960,2.5612770],[39.7015210,2.5612080],[39.7014150,2.5611980],[39.7013210,2.5611720],[39.7014110,2.5609980],[39.7015450,2.5609530],[39.7016380,2.5609990],[39.7017570,2.5610910],[39.7018350,2.5611030],[39.7016610,2.5609560],[39.7015650,2.5608590],[39.7014620,2.5607450],[39.7013700,2.5607000],[39.7012760,2.5606020],[39.7013470,2.5605290],[39.7015100,2.5604890],[39.7014740,2.5603830],[39.7014610,2.5602770],[39.7013750,2.5601990],[39.7012920,2.5600030],[39.7012360,2.5598350],[39.7011690,2.5596920],[39.7011730,2.5595320],[39.7012550,2.5593370],[39.7012980,2.5592070],[39.7012630,2.5590750],[39.7012610,2.5589590],[39.7012930,2.5588190],[39.7012420,2.5586960],[39.7011660,2.5586460],[39.7010510,2.5586560],[39.7009470,2.5586450],[39.7009090,2.5585000],[39.7009830,2.5584460],[39.7009860,2.5583000],[39.7009770,2.5581340],[39.7009120,2.5580240],[39.7007530,2.5580660],[39.7006880,2.5581800],[39.7006110,2.5581980],[39.7005430,2.5581140],[39.7005110,2.5580000],[39.7004280,2.5578760],[39.7003580,2.5578200],[39.7002630,2.5577700],[39.7002920,2.5576500],[39.7002800,2.5574510],[39.7002820,2.5572960],[39.7002560,2.5571390],[39.7001670,2.5571400],[39.7000770,2.5571450],[39.6999800,2.5570930],[39.6999330,2.5569840],[39.6999390,2.5568640],[39.6999540,2.5567320],[39.6999700,2.5566050],[39.6999810,2.5564350],[39.6999090,2.5562690],[39.6998210,2.5561340],[39.6997330,2.5560480],[39.6997260,2.5559200],[39.6997430,2.5558010],[39.6997590,2.5557110],[39.6997180,2.5557170],[39.6997170,2.5556470],[39.6995910,2.5554560],[39.6995070,2.5552710],[39.6994810,2.5550940],[39.6995040,2.5550130],[39.6993900,2.5549790],[39.6992380,2.5549940],[39.6990540,2.5550030],[39.6989590,2.5550210],[39.6988590,2.5550070],[39.6986510,2.5550380],[39.6985410,2.5550620],[39.6984510,2.5550820],[39.6983600,2.5551170],[39.6982430,2.5551280],[39.6981350,2.5551240],[39.6980190,2.5551170],[39.6979080,2.5551170],[39.6978030,2.5551260],[39.6977040,2.5551450],[39.6975240,2.5552210],[39.6974320,2.5552800],[39.6972940,2.5553680],[39.6971440,2.5554830],[39.6970320,2.5555450],[39.6969360,2.5555730],[39.6967750,2.5555390],[39.6966480,2.5555000],[39.6965080,2.5555030],[39.6963930,2.5555430],[39.6962690,2.5556580],[39.6961600,2.5557650],[39.6960620,2.5558450],[39.6959770,2.5559330],[39.6958820,2.5560200],[39.6957910,2.5561370],[39.6957110,2.5562520],[39.6956350,2.5563590],[39.6955590,2.5564610],[39.6954170,2.5565490],[39.6953210,2.5565310],[39.6951140,2.5564450],[39.6950080,2.5563750],[39.6949100,2.5563220],[39.6948120,2.5562510],[39.6946950,2.5561770],[39.6945920,2.5561040],[39.6944820,2.5559870],[39.6944150,2.5558740],[39.6943630,2.5557500],[39.6943040,2.5555790],[39.6942350,2.5554300],[39.6941570,2.5552550],[39.6940690,2.5551830],[39.6939640,2.5551260],[39.6937800,2.5551130],[39.6936770,2.5551370],[39.6935770,2.5551500],[39.6934860,2.5551400],[39.6933140,2.5550330],[39.6932170,2.5548580],[39.6931610,2.5546750],[39.6931080,2.5545730],[39.6930160,2.5544510],[39.6929250,2.5543610],[39.6928430,2.5543040],[39.6927450,2.5542300],[39.6925790,2.5542110],[39.6924730,2.5542180],[39.6923490,2.5542850],[39.6922550,2.5543720],[39.6921620,2.5544120],[39.6920910,2.5543190],[39.6920490,2.5544060],[39.6920450,2.5545450],[39.6920650,2.5546670],[39.6921100,2.5547930],[39.6921390,2.5549230],[39.6920060,2.5550650],[39.6919200,2.5551450],[39.6917620,2.5552910],[39.6916830,2.5553450],[39.6916010,2.5554280],[39.6915250,2.5556280],[39.6914360,2.5557540],[39.6913600,2.5558920],[39.6912670,2.5560020],[39.6911150,2.5560170],[39.6910030,2.5560020],[39.6909200,2.5559310],[39.6908370,2.5558720],[39.6907500,2.5559230],[39.6906910,2.5560230],[39.6907190,2.5561920],[39.6907490,2.5563120],[39.6907900,2.5564190],[39.6908620,2.5565060],[39.6909120,2.5566370],[39.6908240,2.5567870],[39.6907880,2.5568900],[39.6907780,2.5570180],[39.6907240,2.5571490],[39.6906200,2.5572210],[39.6905340,2.5572920],[39.6904600,2.5573740],[39.6904420,2.5574690],[39.6904190,2.5575480],[39.6903310,2.5575890],[39.6902190,2.5576570],[39.6900700,2.5576910],[39.6899790,2.5576880],[39.6898950,2.5576360],[39.6898210,2.5575610],[39.6897020,2.5574110],[39.6895650,2.5572450],[39.6894300,2.5571690],[39.6893350,2.5571200],[39.6892360,2.5570410],[39.6891350,2.5569870],[39.6890650,2.5568760],[39.6889960,2.5568070],[39.6889240,2.5567300],[39.6888420,2.5566630],[39.6887620,2.5566020],[39.6886860,2.5565390],[39.6885690,2.5564410],[39.6885090,2.5563340],[39.6884300,2.5562510],[39.6883430,2.5561560],[39.6882750,2.5560780],[39.6882370,2.5559670],[39.6882340,2.5558660],[39.6881340,2.5557760],[39.6880750,2.5556520],[39.6880060,2.5555810],[39.6878970,2.5555290],[39.6877460,2.5555490],[39.6876650,2.5556110],[39.6875650,2.5556700],[39.6874820,2.5557150],[39.6873910,2.5557770],[39.6873010,2.5559220],[39.6872370,2.5560890],[39.6871790,2.5562670],[39.6871270,2.5564180],[39.6871090,2.5565730],[39.6871030,2.5566900],[39.6870860,2.5568120],[39.6870760,2.5569320],[39.6870720,2.5571220],[39.6870130,2.5572280],[39.6869380,2.5573800],[39.6869140,2.5574920],[39.6868780,2.5576130],[39.6868380,2.5577250],[39.6867970,2.5578500],[39.6867370,2.5579360],[39.6866910,2.5580460],[39.6866930,2.5581690],[39.6867070,2.5582840],[39.6866860,2.5584110],[39.6866600,2.5585610],[39.6866570,2.5586800],[39.6866520,2.5588070],[39.6866570,2.5589850],[39.6866460,2.5591130],[39.6866290,2.5592210],[39.6865750,2.5591240],[39.6865020,2.5590030],[39.6864250,2.5588760],[39.6863480,2.5587030],[39.6862930,2.5585990],[39.6862370,2.5584860],[39.6861790,2.5583970],[39.6861200,2.5582710],[39.6861140,2.5581520],[39.6861300,2.5580250],[39.6860780,2.5580020],[39.6861050,2.5581360],[39.6861650,2.5583130],[39.6862200,2.5584780],[39.6862780,2.5586160],[39.6862400,2.5587130],[39.6861510,2.5585910],[39.6860680,2.5584050],[39.6859850,2.5583060],[39.6858840,2.5581290],[39.6858820,2.5579920],[39.6858270,2.5578590],[39.6857960,2.5577470],[39.6857720,2.5576270],[39.6857810,2.5574690],[39.6858310,2.5573490],[39.6858790,2.5571980],[39.6858220,2.5570290],[39.6857480,2.5569050],[39.6856860,2.5567440],[39.6856510,2.5566350],[39.6855630,2.5566330],[39.6854910,2.5567640],[39.6854710,2.5568890],[39.6853790,2.5569930],[39.6853170,2.5570990],[39.6852670,2.5571920],[39.6852100,2.5572890],[39.6851660,2.5574300],[39.6851510,2.5575510],[39.6851640,2.5576740],[39.6851490,2.5577840],[39.6851930,2.5578940],[39.6852360,2.5580220],[39.6852290,2.5581480],[39.6852780,2.5582670],[39.6853460,2.5584120],[39.6854040,2.5585310],[39.6854780,2.5586060],[39.6855230,2.5587260],[39.6855770,2.5588170],[39.6855790,2.5589520],[39.6856380,2.5591360],[39.6856830,2.5592380],[39.6857430,2.5593330],[39.6858130,2.5594240],[39.6858230,2.5594080],[39.6857480,2.5595020],[39.6857410,2.5596430],[39.6857370,2.5597660],[39.6857540,2.5598860],[39.6857620,2.5600070],[39.6857450,2.5601490],[39.6857170,2.5603190],[39.6856950,2.5604710],[39.6857030,2.5606180],[39.6856960,2.5607530],[39.6857020,2.5608850],[39.6856180,2.5609850],[39.6855420,2.5610900],[39.6854720,2.5612470],[39.6853990,2.5614230],[39.6853370,2.5616260],[39.6852650,2.5618370],[39.6852410,2.5620050],[39.6851580,2.5621710],[39.6851270,2.5623250],[39.6851080,2.5624680],[39.6851230,2.5626300],[39.6851330,2.5627650],[39.6851460,2.5629450],[39.6851610,2.5630920],[39.6851720,2.5632520],[39.6851690,2.5633940],[39.6851580,2.5635260],[39.6852270,2.5634710],[39.6852650,2.5635260],[39.6852710,2.5636550],[39.6852450,2.5637640],[39.6852130,2.5639120],[39.6851750,2.5640170],[39.6851800,2.5641340],[39.6851750,2.5642960],[39.6851820,2.5644790],[39.6852120,2.5646100],[39.6852420,2.5647330],[39.6852340,2.5648870],[39.6851640,2.5650180],[39.6851490,2.5651200],[39.6852710,2.5651640],[39.6853580,2.5651780],[39.6854610,2.5651360],[39.6855520,2.5650990],[39.6855310,2.5652400],[39.6855120,2.5653540],[39.6854810,2.5654840],[39.6855610,2.5654280],[39.6856540,2.5653170],[39.6857430,2.5652260],[39.6858350,2.5651260],[39.6859130,2.5650170],[39.6859400,2.5648940],[39.6860100,2.5648080],[39.6860570,2.5649510],[39.6860220,2.5651360],[39.6861100,2.5651610],[39.6861760,2.5650230],[39.6862220,2.5648670],[39.6862460,2.5647390],[39.6862660,2.5645990],[39.6862770,2.5644800],[39.6863070,2.5643670],[39.6863830,2.5644330],[39.6864630,2.5644220],[39.6865030,2.5642820],[39.6865770,2.5643250],[39.6866430,2.5644150],[39.6867410,2.5644940],[39.6868690,2.5645380],[39.6869590,2.5646330],[39.6870250,2.5647650],[39.6870450,2.5650170],[39.6870760,2.5651450],[39.6871080,2.5652610],[39.6871320,2.5654030],[39.6871700,2.5655160],[39.6872230,2.5656450],[39.6872930,2.5657370],[39.6873940,2.5658070],[39.6875340,2.5658500],[39.6876290,2.5658320],[39.6877260,2.5658490],[39.6877870,2.5659350],[39.6878780,2.5659610],[39.6880010,2.5659520],[39.6880970,2.5659700],[39.6882720,2.5659990],[39.6883930,2.5660480],[39.6884910,2.5660950],[39.6885820,2.5661420],[39.6886880,2.5662040],[39.6887920,2.5662540],[39.6888800,2.5662980],[39.6889870,2.5662960],[39.6891630,2.5663810],[39.6892620,2.5664690],[39.6893310,2.5665490],[39.6894230,2.5666620],[39.6894950,2.5667450],[39.6895890,2.5668680],[39.6896990,2.5670080],[39.6898110,2.5671150],[39.6899110,2.5671880],[39.6900270,2.5671850],[39.6900960,2.5671130],[39.6902060,2.5670990],[39.6903390,2.5671030],[39.6902880,2.5671060],[39.6902120,2.5671570],[39.6903010,2.5671970],[39.6903790,2.5672600],[39.6904410,2.5672360],[39.6904410,2.5671380],[39.6905220,2.5670560],[39.6905360,2.5669540],[39.6906360,2.5670280],[39.6907740,2.5671250],[39.6908670,2.5671600],[39.6909820,2.5672330],[39.6910590,2.5672950],[39.6911150,2.5673850],[39.6911930,2.5674820],[39.6912630,2.5675780],[39.6913290,2.5676810],[39.6914080,2.5678150],[39.6914700,2.5679250],[39.6915520,2.5680010],[39.6916470,2.5680660],[39.6917400,2.5680760],[39.6918300,2.5680270],[39.6919760,2.5679650],[39.6921160,2.5678620],[39.6922250,2.5677900],[39.6922630,2.5676100],[39.6922630,2.5674410],[39.6922770,2.5673110],[39.6923310,2.5671640],[39.6924280,2.5670410],[39.6925490,2.5669840],[39.6926700,2.5669640],[39.6927600,2.5669870],[39.6928240,2.5669210],[39.6928620,2.5668060],[39.6928290,2.5666940],[39.6927570,2.5666200],[39.6927320,2.5665140],[39.6926680,2.5664140],[39.6926900,2.5664530],[39.6927420,2.5666020],[39.6928040,2.5666770],[39.6928710,2.5667670],[39.6929560,2.5668160],[39.6930790,2.5667940],[39.6931730,2.5667920],[39.6932730,2.5668340],[39.6933790,2.5669080],[39.6935050,2.5669860],[39.6935640,2.5670900],[39.6936510,2.5671630],[39.6936830,2.5673360],[39.6937140,2.5675250],[39.6937670,2.5676430],[39.6938170,2.5677360],[39.6938800,2.5678860],[39.6939650,2.5680530],[39.6940530,2.5682770],[39.6941260,2.5684810],[39.6941930,2.5686300],[39.6942740,2.5687790],[39.6943950,2.5689770],[39.6944970,2.5691120],[39.6945670,2.5691980],[39.6946350,2.5692940],[39.6946990,2.5694010],[39.6947280,2.5695310],[39.6947300,2.5696870],[39.6946750,2.5698530],[39.6945830,2.5700020],[39.6945010,2.5700890],[39.6944050,2.5701740],[39.6943300,2.5702680],[39.6943100,2.5704500],[39.6943050,2.5705800],[39.6942850,2.5706950],[39.6942610,2.5708350],[39.6941850,2.5708230],[39.6942290,2.5708410],[39.6942460,2.5709390],[39.6942530,2.5711240],[39.6941950,2.5712560],[39.6941360,2.5714360],[39.6941150,2.5715580],[39.6942200,2.5715760],[39.6943320,2.5716700],[39.6944030,2.5717600],[39.6944890,2.5717800],[39.6945770,2.5718470],[39.6945960,2.5719570],[39.6946140,2.5721060],[39.6946780,2.5721980],[39.6946530,2.5722960],[39.6945990,2.5724410],[39.6946750,2.5725580],[39.6947340,2.5725850],[39.6947910,2.5726790],[39.6948920,2.5727970],[39.6949760,2.5728770],[39.6950600,2.5729460],[39.6951580,2.5729780],[39.6952650,2.5730230],[39.6953460,2.5730900],[39.6954240,2.5731780],[39.6955070,2.5732940],[39.6956120,2.5734710],[39.6956520,2.5735800],[39.6957040,2.5737090],[39.6957050,2.5739090],[39.6958100,2.5738970],[39.6958870,2.5740120],[39.6958880,2.5741390],[39.6958650,2.5742560],[39.6958550,2.5744350],[39.6957800,2.5746550],[39.6957410,2.5747930],[39.6956910,2.5749070],[39.6957180,2.5749790],[39.6958240,2.5749300],[39.6959080,2.5748540],[39.6960240,2.5748070],[39.6960170,2.5749220],[39.6959500,2.5750690],[39.6959480,2.5751760],[39.6960360,2.5751780],[39.6962020,2.5752300],[39.6963050,2.5752370],[39.6964250,2.5753210],[39.6965500,2.5753720],[39.6966480,2.5754080],[39.6967470,2.5754050],[39.6968610,2.5754150],[39.6969770,2.5754600],[39.6970990,2.5754940],[39.6972480,2.5755550],[39.6973580,2.5756070],[39.6974640,2.5756210],[39.6976020,2.5756670],[39.6977320,2.5756930],[39.6978780,2.5757640],[39.6979950,2.5757430],[39.6981040,2.5757450],[39.6981880,2.5758100],[39.6982620,2.5758760],[39.6983960,2.5759530],[39.6985040,2.5759030],[39.6985970,2.5758350],[39.6987030,2.5758340],[39.6987090,2.5759610],[39.6987780,2.5761270],[39.6988250,2.5762330],[39.6988980,2.5763690],[39.6989390,2.5764900],[39.6990290,2.5765940],[39.6992180,2.5765710],[39.6993920,2.5765590],[39.6995210,2.5764900],[39.6995970,2.5764110],[39.6996880,2.5763150],[39.6998010,2.5762710],[39.6999200,2.5763310],[39.6999500,2.5763800],[39.6999770,2.5765380],[39.7000010,2.5766530],[39.7000220,2.5767820],[39.7000410,2.5770170],[39.7000620,2.5772780],[39.7000930,2.5775270],[39.7001100,2.5776590],[39.7000670,2.5777710],[39.7000070,2.5778470],[39.7000050,2.5779260],[39.6999950,2.5779590],[39.6999910,2.5781310],[39.7000270,2.5782830],[39.7000490,2.5784790],[39.7001020,2.5786550],[39.7001490,2.5787220],[39.7001590,2.5785540],[39.7001330,2.5783930],[39.7001060,2.5782790],[39.7000620,2.5780990],[39.7000630,2.5778910],[39.7001420,2.5776820],[39.7002550,2.5775030],[39.7003300,2.5773990],[39.7003420,2.5773150],[39.7004710,2.5771570],[39.7005390,2.5770740],[39.7005980,2.5769700],[39.7007100,2.5768570],[39.7008110,2.5767690],[39.7009050,2.5767010],[39.7010310,2.5766560],[39.7011610,2.5766150],[39.7012550,2.5766050],[39.7014620,2.5766580],[39.7015880,2.5767010],[39.7017100,2.5767370],[39.7018300,2.5767530],[39.7019280,2.5767800],[39.7020670,2.5768190],[39.7022620,2.5768940],[39.7023840,2.5769600],[39.7024910,2.5770550],[39.7025940,2.5771600]],\r\n\t\t\t\t\tgraphDist          : [0.00,12.30,22.57,34.48,45.98,57.26,67.84,79.88,90.90,102.24,115.69,128.10,138.61,149.57,159.89,175.99,188.57,200.55,210.86,223.42,239.15,250.15,262.36,272.44,285.78,301.06,313.07,325.03,336.69,349.59,362.90,373.49,385.12,396.16,406.36,420.21,433.35,446.36,459.58,472.22,482.75,496.74,509.81,524.88,538.60,550.21,563.13,575.05,585.36,596.55,607.69,618.74,628.99,644.68,660.66,676.68,690.98,704.90,719.30,730.16,740.59,751.12,762.25,774.10,790.07,800.58,814.53,825.33,837.08,849.87,862.22,875.25,886.28,897.45,911.72,924.13,934.92,949.13,960.59,971.15,983.04,996.58,1011.67,1034.32,1045.85,1056.39,1076.21,1092.61,1107.31,1123.45,1136.30,1149.56,1160.41,1174.03,1190.85,1206.77,1219.16,1236.51,1251.56,1264.92,1277.05,1288.31,1303.53,1313.62,1328.05,1339.30,1352.11,1367.03,1385.27,1397.25,1408.43,1423.38,1437.13,1449.14,1467.35,1478.09,1490.91,1501.64,1511.87,1529.61,1542.54,1553.90,1564.02,1575.07,1585.78,1603.18,1620.82,1632.00,1642.05,1660.57,1671.67,1684.35,1697.56,1711.25,1730.17,1740.86,1755.81,1770.35,1781.39,1792.98,1807.15,1818.34,1831.93,1843.21,1856.87,1869.54,1882.54,1902.59,1913.59,1935.87,1948.80,1963.73,1977.83,1991.78,2004.54,2025.49,2042.33,2058.43,2071.32,2084.84,2099.43,2113.86,2133.28,2149.04,2162.19,2184.33,2199.76,2213.59,2227.92,2238.75,2252.15,2263.31,2274.96,2285.91,2306.40,2316.69,2326.85,2340.36,2350.77,2365.45,2379.26,2391.81,2410.63,2425.08,2441.11,2453.34,2474.17,2489.24,2501.78,2512.41,2523.34,2533.91,2545.58,2556.93,2567.01,2577.59,2588.83,2605.03,2620.59,2633.61,2645.10,2665.65,2680.53,2692.51,2715.09,2726.10,2737.71,2755.54,2765.60,2776.09,2787.57,2799.26,2816.72,2835.90,2847.40,2858.27,2873.75,2894.50,2906.16,2923.85,2934.05,2944.75,2955.92,2971.92,2982.58,2996.17,3010.57,3022.76,3035.74,3055.79,3067.37,3085.72,3107.30,3125.24,3141.03,3160.77,3172.04,3185.90,3203.81,3218.73,3230.37,3246.76,3258.10,3270.41,3287.72,3302.35,3317.34,3331.17,3349.95,3360.39,3380.39,3394.65,3404.95,3416.35,3430.55,3442.78,3456.57,3468.94,3479.19,3489.79,3502.89,3515.36,3526.16,3547.26,3558.97,3570.19,3582.38,3594.77,3606.27,3620.11,3631.11,3641.98,3653.95,3664.40,3676.80,3688.74,3702.08,3716.19,3729.95,3740.79,3757.36,3771.46,3783.64,3794.52,3808.54,3821.96,3832.49,3844.52,3855.37,3866.24,3877.14,3887.82,3901.32,3916.80,3927.10,3939.75,3951.00,3962.33,3977.14,3990.94,4005.62,4020.87,4039.35,4053.13,4063.18,4075.88,4086.13,4097.26,4111.83,4125.47,4138.05,4151.55,4162.12,4173.06,4183.46,4195.55,4210.19,4221.60,4238.08,4251.54,4264.71,4283.37,4300.89,4315.17,4333.75,4349.50,4364.04,4383.43,4396.87,4409.73,4424.85,4442.26,4464.54,4483.09,4498.75,4510.24,4524.64,4538.48,4550.14,4572.17,4589.63,4602.17,4613.55,4630.33,4641.08,4652.67,4664.90,4678.77,4688.89,4699.34,4710.64,4721.96,4736.09,4746.40,4758.22,4768.94,4789.66,4805.17,4816.35,4831.90,4842.64,4866.37,4880.03,4895.21,4906.26,4921.65,4931.87,4950.48,4961.11,4971.66,4988.07,5007.62,5023.42,5037.83,5052.58,5071.60,5083.76,5095.80,5105.90,5118.71,5131.54,5141.74,5154.85,5167.16,5181.36,5193.80,5207.54,5221.80,5234.85,5253.40,5265.74,5276.03,5286.81,5297.46,5312.85,5323.16,5336.98,5347.81,5365.24,5378.60,5393.37,5403.46,5413.50,5425.48,5436.20,5446.49,5457.91,5469.03,5484.46,5500.78,5515.95,5528.47,5540.10,5550.83,5561.54,5573.05,5584.04,5605.73,5624.49,5639.92,5649.98,5664.03,5681.41,5702.22,5713.05,5724.32,5747.79,5760.25,5770.45,5781.12,5794.19,5806.23,5819.14,5831.49,5843.19,5854.32,5875.38,5886.79,5903.94,5923.34,5936.90,5947.87,5966.02,5980.52,5996.10,6009.33,6026.28,6041.48,6054.40,6066.62,6079.59,6093.86,6107.14,6119.61,6131.78,6149.28,6160.06,6184.27,6197.50,6209.36,6221.87,6236.38,6249.43,6265.23,6277.44,6289.53,6305.58,6320.46,6337.76,6349.41,6362.22,6383.37,6395.34,6406.56,6416.73,6438.07,6457.11,6474.05,6484.60,6499.37,6512.19,6522.69,6535.35,6554.70,6566.56,6581.62,6594.56,6605.45,6616.70,6626.99,6639.15,6650.03,6662.25,6674.63,6694.10,6706.34,6728.08,6738.15,6750.19,6769.54,6784.25,6799.07,6813.32,6830.90,6843.72,6854.78,6865.80,6879.31,6890.88,6905.86,6916.82,6927.38,6938.82,6952.00,6969.02,6980.22,6991.53,7007.54,7020.80,7032.99,7046.71,7064.00,7074.95,7085.60,7099.96,7117.01,7127.18,7137.73,7148.21,7166.86,7188.01,7204.64,7216.12,7229.23,7241.95,7255.18,7265.31,7275.96,7287.42,7298.20,7308.36,7324.43,7336.05,7347.62,7360.77,7371.31,7384.56,7396.93,7411.46,7426.98,7437.27,7451.15,7469.03,7480.20,7492.70,7503.47,7515.37,7531.99,7548.08,7564.93,7579.49,7593.28,7603.74,7614.59,7625.29,7641.87,7654.77,7671.91,7682.14,7693.36,7704.31,7715.98,7725.99,7736.86,7747.65,7758.34,7770.28,7783.82,7794.25,7805.72,7821.36,7832.85,7845.42,7856.31,7869.64,7883.72,7900.94,7911.85,7923.36,7933.50,7946.13,7956.67,7970.19,7981.06,7993.19,8009.92,8025.43,8039.01,8052.55,8067.66,8086.08,8098.91,8117.92,8130.75,8143.71,8153.97,8164.59,8178.44,8190.35,8204.84,8220.76,8235.65,8251.14,8261.37,8271.65,8285.77,8297.03,8311.10,8323.43,8333.90,8345.31,8359.10,8370.16,8381.68,8392.01,8402.71,8414.85,8426.31,8438.37,8453.11,8465.44,8476.16,8488.17,8498.61,8510.71,8528.12,8538.18,8548.77,8561.88,8573.91,8586.07,8598.32,8609.50,8620.27,8630.76,8643.12,8658.42,8672.19,8685.34,8697.38,8709.18,8723.46,8735.84,8751.63,8769.18,8788.47,8808.42,8824.70,8841.78,8855.46,8868.07,8882.41,8894.35,8910.13,8923.01,8937.20,8949.61,8961.11,8972.51,8983.06,8994.47,9004.66,9017.98,9028.00,9038.21,9052.34,9068.34,9080.26,9091.52,9105.21,9119.17,9130.09,9144.79,9154.88,9167.27,9179.31,9192.11,9202.42,9214.24,9225.22,9239.47,9252.35,9265.86,9278.81,9289.78,9302.21,9316.60,9333.01,9344.87,9359.01,9373.30,9384.78,9397.12,9407.41,9418.31,9431.34,9444.18,9458.04,9468.20,9479.22,9492.45,9507.31,9520.48,9534.57,9556.87,9568.71,9579.65,9592.55,9603.57,9616.73,9628.30,9641.12,9657.20,9667.98,9679.00,9689.35,9699.91,9713.69,9724.50,9744.41,9758.58,9770.21,9781.11,9794.04,9806.39,9816.90,9828.97,9850.14,9863.53,9873.83,9887.95,9898.72,9913.59,9930.74,9946.28,9959.11,9972.23,9982.31,9994.80,10010.07,10023.46,10033.66,10046.34,10056.86,10068.29,10078.48,10090.89,10100.93,10114.62,10132.17,10143.00,10157.26,10167.44,10177.53,10189.70,10201.09,10212.58,10227.16,10238.89,10250.14,10262.08,10272.50,10283.36,10300.44,10318.45,10332.11,10349.65,10364.14,10375.39,10389.33,10404.40,10418.72,10432.50,10442.79,10453.95,10467.09,10478.97,10489.26,10500.57,10513.77,10525.71,10540.88,10551.49,10562.69,10573.26,10587.39,10598.84,10611.42,10625.29,10643.32,10654.49,10667.46,10684.24,10702.70,10715.49,10726.32,10741.70,10758.95,10780.48,10799.74,10814.51,10830.12,10851.76,10867.95,10878.66,10889.83,10901.43,10913.01,10926.36,10941.84,10958.24,10970.09,10983.69,10996.09,11011.87,11023.01,11033.11,11045.50,11060.34,11071.93,11082.55,11098.55,11111.62,11128.36,11140.42,11152.32,11168.01,11179.55,11189.56,11202.37,11213.22,11226.61,11237.27,11248.09,11262.24,11277.69,11287.78,11298.03,11313.23,11325.14,11336.30,11347.71,11360.47,11371.29,11382.99,11396.66,11416.30,11426.73,11439.32,11456.51,11469.52,11483.32,11494.26,11504.64,11520.34,11541.07,11553.68,11564.91,11577.43,11590.80,11602.26,11616.33,11627.29,11641.91,11652.76,11663.45,11683.28,11694.92,11711.01,11725.75,11737.10,11748.13,11762.12,11776.16,11790.08,11807.60,11820.62,11832.52,11848.53,11863.21,11880.56,11894.36,11906.56,11917.47,11927.50,11944.28,11957.38,11970.02,11982.92,11994.12,12010.59,12021.06,12035.25,12046.56,12062.90,12084.13,12103.53,12119.75,12130.59,12143.74,12157.80,12172.01,12183.09,12197.31,12207.51,12218.91,12239.14,12261.70,12283.46,12294.92,12306.05,12316.30,12329.39,12342.83,12357.70,12371.31,12388.28,12404.53,12416.57,12431.13,12445.23,12455.43,12471.69,12489.77,12509.76,12529.58,12541.77,12552.74,12572.52,12582.90,12594.68,12610.74,12624.33,12636.30,12650.88,12665.84,12676.37,12699.85,12714.35,12728.26,12741.67,12752.81,12768.62,12791.38,12806.07,12820.51,12835.19],\r\n\t\t\t\t\tgraphEle           : [427.00,425.20,422.20,418.20,415.00,411.40,409.80,411.60,411.00,406.60,403.80,401.80,396.20,394.60,399.80,397.40,396.00,390.20,384.40,379.60,369.80,367.80,366.60,363.40,361.60,356.20,352.60,346.60,345.20,343.60,338.40,336.60,332.60,328.40,326.60,320.00,311.40,305.00,302.80,295.80,288.20,280.40,274.80,274.60,281.80,287.20,289.80,285.60,287.80,285.40,290.80,290.60,294.60,291.00,284.80,281.60,276.40,272.00,267.40,265.60,264.00,264.40,262.60,259.20,256.60,252.60,245.00,239.60,233.60,225.80,222.80,220.20,216.60,215.20,211.60,209.60,207.00,205.00,205.20,204.40,204.40,203.80,205.80,208.60,208.60,206.40,205.80,203.40,200.40,196.40,196.60,195.40,194.60,192.60,191.80,190.40,186.60,184.00,183.00,187.60,193.00,192.40,191.40,190.80,187.80,184.40,180.60,177.20,173.60,171.80,170.60,166.80,165.20,165.20,165.80,164.60,164.20,163.60,165.60,165.80,167.00,164.00,160.60,156.20,152.40,148.60,144.20,139.20,137.20,134.40,136.40,134.40,132.80,132.80,132.60,132.00,132.20,131.40,131.60,133.00,134.60,137.60,138.40,140.40,142.20,141.60,140.40,136.80,135.20,132.00,132.80,134.40,136.60,136.20,133.20,131.00,128.40,125.60,126.60,125.80,125.80,124.80,125.80,128.00,127.40,120.20,116.80,114.60,112.20,109.80,108.80,109.60,110.20,109.40,101.60,102.00,104.20,102.40,100.20,99.40,100.60,100.20,96.00,94.40,92.00,92.00,92.00,92.60,93.80,95.20,95.60,94.40,93.00,93.40,92.20,90.20,90.60,91.00,89.20,87.60,86.00,82.80,80.60,79.00,78.40,76.80,75.80,75.40,76.20,76.80,76.20,75.00,73.00,67.20,66.40,64.20,62.00,58.20,56.80,54.20,53.60,52.40,51.80,49.80,49.00,47.60,47.00,47.20,46.40,48.60,50.00,50.80,49.80,49.20,48.60,49.20,49.40,48.20,46.60,44.40,42.20,41.60,41.60,40.40,38.80,36.00,32.80,30.60,29.00,28.80,28.20,26.40,24.00,22.40,19.60,18.80,16.80,15.20,13.80,14.40,11.60,11.00,12.40,16.80,18.60,15.80,18.40,19.00,18.60,13.80,12.20,10.80,9.20,10.00,10.60,13.80,18.40,23.80,28.00,29.00,30.20,31.20,31.80,34.20,35.00,36.60,38.20,38.80,40.60,44.20,47.00,47.00,48.00,49.00,49.60,50.40,50.80,51.00,50.80,51.00,52.40,54.40,56.80,58.80,59.60,60.00,61.20,62.00,62.60,63.40,64.00,65.00,65.80,66.60,68.00,69.00,70.00,70.60,70.80,71.00,71.40,73.00,74.40,74.60,76.20,79.00,81.60,82.20,81.60,81.60,81.60,80.20,77.20,74.40,71.80,71.00,70.40,69.40,68.40,68.00,66.40,65.00,63.60,61.40,60.00,58.80,60.20,62.20,63.20,61.40,59.80,58.20,56.20,54.80,54.40,53.60,51.20,51.20,52.80,55.00,55.60,52.80,50.80,48.80,48.00,46.80,46.80,48.40,47.00,46.00,43.80,39.80,38.20,37.00,37.00,36.40,35.20,34.80,33.80,32.40,32.80,34.00,36.60,38.80,39.60,38.00,37.80,38.60,40.40,43.40,44.20,45.00,46.40,46.60,46.80,47.00,46.20,45.00,43.00,41.80,40.40,39.40,38.60,38.00,37.20,37.00,36.60,36.40,35.00,34.20,33.20,33.40,30.80,28.00,25.60,26.80,25.40,25.40,24.60,24.80,23.80,26.80,30.60,34.00,35.80,37.20,40.20,41.40,42.40,44.00,44.80,45.60,46.00,46.40,46.80,47.00,47.40,47.80,48.60,49.80,50.60,51.40,52.20,52.20,51.80,51.80,52.40,53.20,54.40,56.20,57.40,58.40,59.00,59.60,60.40,61.00,61.00,62.00,62.60,63.80,64.80,65.80,66.40,66.20,65.80,65.40,64.60,64.20,64.20,65.60,67.60,72.20,75.00,76.00,76.60,78.20,79.20,79.20,79.80,82.00,83.60,85.40,86.20,89.00,90.20,92.20,93.20,93.60,93.00,93.60,95.00,96.40,98.40,101.00,104.40,107.80,110.20,111.60,115.00,117.80,119.00,121.40,124.00,124.40,125.80,126.00,128.80,133.60,137.80,137.60,136.00,133.60,131.20,131.80,136.40,139.60,141.20,144.00,144.80,149.20,153.80,153.60,154.60,156.60,160.60,163.40,164.00,164.80,165.60,168.00,171.40,173.80,175.20,177.40,178.80,181.60,183.60,186.00,188.00,189.80,191.40,194.80,197.20,199.60,202.40,204.80,207.60,209.80,213.40,217.60,220.60,224.00,227.60,229.00,231.40,234.00,237.20,240.20,242.20,245.40,248.60,251.20,252.80,255.00,257.60,258.80,263.60,270.60,272.60,274.20,275.20,276.20,277.40,275.60,273.20,270.60,270.80,272.80,274.80,278.40,281.80,284.60,287.80,290.20,292.20,294.60,296.60,298.20,298.60,300.40,301.00,298.80,295.20,297.60,298.80,299.00,300.00,300.20,306.60,310.60,310.00,312.80,313.60,309.40,309.60,309.00,309.00,308.60,307.60,307.40,309.40,310.20,309.00,308.20,308.40,311.00,313.40,316.40,319.80,323.00,326.00,329.40,332.00,333.80,336.40,337.40,338.60,341.40,343.20,344.80,346.00,346.60,348.40,349.60,351.20,351.80,352.20,352.60,352.60,352.20,354.00,356.00,357.60,359.60,360.80,362.00,364.60,367.20,369.60,372.00,374.60,376.60,377.40,380.00,383.00,386.60,386.40,387.60,385.40,386.60,388.40,391.40,393.80,396.40,398.60,401.20,403.40,405.20,406.40,408.40,410.80,412.00,413.80,414.20,415.60,417.20,420.00,422.20,424.40,426.40,426.80,428.20,432.20,434.80,437.00,439.40,440.80,442.20,443.40,444.60,446.20,448.40,450.60,452.20,453.00,455.20,458.20,458.60,462.80,463.60,463.80,463.60,464.40,464.20,464.60,467.60,470.20,469.60,472.00,474.60,477.60,479.40,481.80,484.80,489.60,492.40,495.00,497.80,500.80,504.40,507.20,508.80,510.00,510.80,512.40,514.80,516.40,516.80,517.60,518.80,520.20,520.80,521.40,521.80,521.00,520.40,518.40,515.80,514.60,514.00,513.20,512.60,511.60,510.40,508.80,507.40,505.00,502.80,500.60,496.80,498.40,501.20,500.00,499.40,497.60,495.40,491.20,487.80,487.20,486.60,485.40,484.40,484.40,485.80,487.40,488.20,489.00,490.60,491.80,492.20,492.00,491.00,490.80,490.60,490.60,490.60,490.20,489.20,488.60,488.00,487.60,487.20,485.40,484.60,481.40,476.20,471.40,470.80,467.20,465.20,466.00,470.60,471.40,474.60,476.60,478.20,475.20,471.00,467.40,458.40,457.60,453.00,458.20,464.60,469.80,474.60,477.40,476.60,477.20,478.00,478.40,478.00,477.20,477.00,476.60,476.20,476.00,476.20,476.60,477.40,478.80,480.20,482.00,483.40,484.00,484.40,484.80,485.20,486.60,485.80,485.20,483.60,484.00,483.80,483.60,482.40,480.80,480.20,479.40,478.20,478.20,478.60,477.80,479.20,481.60,481.00,480.20,479.80,478.60,477.00,475.40,473.40,471.20,469.80,468.40,466.80,464.60,463.20,461.60,461.00,458.80,456.20,455.40,454.40,452.00,450.60,449.60,449.20,447.60,444.60,444.20,441.40,439.80,439.20,438.20,436.60,432.80,431.80,430.60,430.40,430.40,430.00,429.40,429.20,428.40,427.20,426.60,425.60,425.20,425.20,425.80,425.20,424.40,425.40,426.20,427.00,425.00,423.40,422.80,423.20,423.60,423.40,423.20,423.60,425.00,426.20,425.60,425.20,425.00,425.40,425.00,425.60,425.60,426.20,426.60,427.20,428.00,428.20,429.20,429.20,429.00,430.80,432.00,432.60,434.60,435.00,436.00,436.20,435.40,434.60,434.00,433.80,433.00,430.20,429.40,429.60,430.00,430.00,430.20,430.80,431.80,431.60,431.40,431.00,430.00,428.80,427.80,427.40,428.00,428.40,428.40,428.60,428.20,425.80,425.80,426.60,428.40],\r\n\t\t\t\t\tgraphSpeed         : [],\r\n\t\t\t\t\tgraphHr            : [],\r\n\t\t\t\t\tgraphAtemp         : [],\r\n\t\t\t\t\tgraphCad           : [],\r\n\t\t\t\t\tgraphGrade         : [],\r\n\t\t\t\t\twaypoints          : [],\r\n\t\t\t\t\tunit               : \"0\",\r\n\t\t\t\t\tunitspeed          : \"0\",\r\n\t\t\t\t\tcolor1             : [\"#3366cc\"],\r\n\t\t\t\t\tcolor2             : \"#3366cc\",\r\n\t\t\t\t\tcolor3             : \"#ff0000\",\r\n\t\t\t\t\tcolor4             : \"#ff77bd\",\r\n\t\t\t\t\tcolor5             : \"#beecff\",\r\n\t\t\t\t\tcolor6             : \"#beecff\",\r\n\t\t\t\t\tcolor7             : \"#ff77bd\",\r\n\t\t\t\t\tchartFrom1         : \"\",\r\n\t\t\t\t\tchartTo1           : \"\",\r\n\t\t\t\t\tchartFrom2         : \"\",\r\n\t\t\t\t\tchartTo2           : \"\",\r\n\t\t\t\t\tstartIcon          : \"\",\r\n\t\t\t\t\tendIcon            : \"\",\r\n\t\t\t\t\tcurrentIcon        : \"\",\r\n\t\t\t\t\twaypointIcon       : \"\",\r\n\t\t\t\t\tcurrentpositioncon : \"\",\r\n\t\t\t\t\tusegpsposition     : \"\",\r\n\t\t\t\t\tzoomOnScrollWheel  : \"\",\r\n\t\t\t\t\tngGalleries        : [],\r\n\t\t\t\t\tngImages           : [],\r\n\t\t\t\t\tpluginUrl          : \"https:\/\/trailrunningmallorca.es\/wp-content\/plugins\",\r\n\t\t\t\t\tTFApiKey           : \"\",\r\n\t\t\t\t\tMapBoxApiKey           : \"\",\r\n\t\t\t\t\tlangs              : {\r\n\t\t\t\t\t\taltitude        : \"Altitud\",\r\n\t\t\t\t\t\tcurrentPosition : \"Posici\u00f3n actual\",\r\n\t\t\t\t\t\tspeed           : \"Velocidad\",\r\n\t\t\t\t\t\tgrade           : \"Grados\",\r\n\t\t\t\t\t\theartRate       : \"Pulso card\u00edaco\",\r\n\t\t\t\t\t\tatemp           : \"Temperatura\",\r\n\t\t\t\t\t\tcadence         : \"Cadencia\",\r\n\t\t\t\t\t\tgoFullScreen    : \"Ir a pantalla completa\",\r\n\t\t\t\t\t\texitFullFcreen  : \"Salir de la pantalla completa\",\r\n\t\t\t\t\t\thideImages      : \"Ocultar im\u00e1genes\",\r\n\t\t\t\t\t\tshowImages      : \"Mostrar im\u00e1genes\",\r\n\t\t\t\t\t\tbackToCenter\t: \"Volver al centro\"\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\r\n\t\t\t});\r\n\r\n\t\t<\/script>Download file: <a href='https:\/\/trailrunningmallorca.es\/wp-content\/uploads\/gpx\/valldemossa\/hort-cova.gpx' target='_new' download>hort-cova.gpx<\/a>\n\n<\/div><h2 class=\"tabtitle\">Wikiloc<\/h2>\n<div class=\"tabcontent\">\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/es.wikiloc.com\/wikiloc\/spatialArtifacts.do?event=view&amp;id=133564925&amp;measures=on&amp;title=off&amp;near=on&amp;images=off&amp;maptype=T\" width=\"100%\" height=\"700\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nota Importante: Pueden haber problemas de paso en la esplanada para ir hacia el Mirador dels Coloms, est\u00e1 en obras y hace pinta que lo van a cerrar. Itinerario U La ruta se inicia en la Urbanizaci\u00f3n George Sand, aparcamos&hellip; <\/p>\n","protected":false},"author":1,"featured_media":14868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":7578,"footnotes":""},"categories":[1801,1793,5,18],"tags":[1352,385,1353,1357,1351,1356,386,1355,384,1350,1354],"class_list":["post-14865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entre-10-km-y-15-km","category-moderado","category-tramuntana-central","category-valldemossa","tag-cami-de-short-de-sa-cova","tag-cami-des-pescadors","tag-finca-de-son-sales","tag-font-de-sa-cova","tag-mirador-de-sa-cova","tag-mirador-des-coloms","tag-mirant-de-mar","tag-pla-de-ses-piotes","tag-port-des-canonge","tag-urbanizacion-george-sand","tag-urbanizacion-nova-valldemossa"],"_links":{"self":[{"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/posts\/14865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/comments?post=14865"}],"version-history":[{"count":1,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/posts\/14865\/revisions"}],"predecessor-version":[{"id":21347,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/posts\/14865\/revisions\/21347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/media\/14868"}],"wp:attachment":[{"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/media?parent=14865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/categories?post=14865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trailrunningmallorca.es\/index.php\/wp-json\/wp\/v2\/tags?post=14865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}